{"id":29181,"date":"2022-08-16T11:43:03","date_gmt":"2022-08-16T09:43:03","guid":{"rendered":"https:\/\/www.wicam.com\/cadcam-nesting-software\/pncalculate\/calculate-locally\/"},"modified":"2024-05-28T15:09:11","modified_gmt":"2024-05-28T13:09:11","slug":"calcolo-locale","status":"publish","type":"page","link":"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/","title":{"rendered":"Calcolo locale"},"content":{"rendered":"<h2>Calcolare localmente<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-22910\" src=\"https:\/\/www.wicam.com\/wp-content\/uploads\/2022\/03\/cloud-300x278.png\" alt=\"\" width=\"375\" height=\"348\" srcset=\"https:\/\/wicam.com\/wp-content\/uploads\/2022\/03\/cloud-300x278.png 300w, https:\/\/wicam.com\/wp-content\/uploads\/2022\/03\/cloud-768x712.png 768w, https:\/\/wicam.com\/wp-content\/uploads\/2022\/03\/cloud.png 1000w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/>Stai cercando una soluzione che ti permetta di calcolare localmente e in modo specifico per la macchina? Allora abbiamo lo strumento giusto per voi.<\/p>\n<p>Vi offriamo una soluzione basata su server che vi permette di calcolare i vostri prezzi in pochi secondi utilizzando un&#8217;applicazione desktop &#8211; direttamente dal vostro sistema ERP\/PPS, se lo desiderate.<\/p>\n<h4 style=\"text-align: left;\">Funzioni di base<\/h4>\n<ul>\n<li>Elaborazione di file 3D<\/li>\n<li>Elaborazione e smontaggio di assiemi<\/li>\n<li>Calcolo di singole parti<\/li>\n<li>Calcolo di assiemi<\/li>\n<li>Conversione di file CAD in altri formati<\/li>\n<\/ul>\n<p><a class=\"btn\" href=\"https:\/\/www.wicam.com\/it\/contatto\/\">Richiesta di un appuntamento per una demo online<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Calcolare localmente Stai cercando una soluzione che ti permetta di calcolare localmente e in modo specifico per la macchina? Allora abbiamo lo strumento giusto per voi. Vi offriamo una soluzione basata su server che vi permette di calcolare i vostri prezzi in pochi secondi utilizzando un&#8217;applicazione desktop &#8211; direttamente dal vostro sistema ERP\/PPS, se lo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":28917,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-software-single.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-29181","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CAD\/CAM Nesting Software - Calcolo locale - PNCalculate - WiCAM<\/title>\n<meta name=\"description\" content=\"Salvate i parametri di produzione e la formula di calcolo una volta sola e in futuro i vostri clienti potranno ordinare i pezzi da voi in pochi secondi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAD\/CAM Nesting Software - Calcolo locale - PNCalculate - WiCAM\" \/>\n<meta property=\"og:description\" content=\"Salvate i parametri di produzione e la formula di calcolo una volta sola e in futuro i vostri clienti potranno ordinare i pezzi da voi in pochi secondi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/\" \/>\n<meta property=\"og:site_name\" content=\"WiCAM\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-28T13:09:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.wicam.com\/wp-content\/uploads\/2022\/03\/cloud-300x278.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/wicam.com\\\/it\\\/cadcam-nesting-software\\\/pncalculate\\\/calcolo-locale\\\/\",\"url\":\"https:\\\/\\\/wicam.com\\\/it\\\/cadcam-nesting-software\\\/pncalculate\\\/calcolo-locale\\\/\",\"name\":\"CAD\\\/CAM Nesting Software - Calcolo locale - PNCalculate - WiCAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/wicam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/wicam.com\\\/it\\\/cadcam-nesting-software\\\/pncalculate\\\/calcolo-locale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/wicam.com\\\/it\\\/cadcam-nesting-software\\\/pncalculate\\\/calcolo-locale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.wicam.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cloud-300x278.png\",\"datePublished\":\"2022-08-16T09:43:03+00:00\",\"dateModified\":\"2024-05-28T13:09:11+00:00\",\"description\":\"Salvate i parametri di produzione e la formula di calcolo una volta sola e in futuro i vostri clienti potranno ordinare i pezzi da voi in pochi secondi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/wicam.com\\\/it\\\/cadcam-nesting-software\\\/pncalculate\\\/calcolo-locale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/wicam.com\\\/it\\\/cadcam-nesting-software\\\/pncalculate\\\/calcolo-locale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/wicam.com\\\/it\\\/cadcam-nesting-software\\\/pncalculate\\\/calcolo-locale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.wicam.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cloud-300x278.png\",\"contentUrl\":\"https:\\\/\\\/www.wicam.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/cloud-300x278.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/wicam.com\\\/it\\\/cadcam-nesting-software\\\/pncalculate\\\/calcolo-locale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/wicam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Software\",\"item\":\"https:\\\/\\\/wicam.com\\\/it\\\/cadcam-nesting-software\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Calcolo\",\"item\":\"https:\\\/\\\/wicam.com\\\/it\\\/cadcam-nesting-software\\\/pncalculate\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Calcolo locale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/wicam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/wicam.com\\\/it\\\/\",\"name\":\"WiCAM\",\"description\":\"Technische Software\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/wicam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAD\/CAM Nesting Software - Calcolo locale - PNCalculate - WiCAM","description":"Salvate i parametri di produzione e la formula di calcolo una volta sola e in futuro i vostri clienti potranno ordinare i pezzi da voi in pochi secondi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/","og_locale":"it_IT","og_type":"article","og_title":"CAD\/CAM Nesting Software - Calcolo locale - PNCalculate - WiCAM","og_description":"Salvate i parametri di produzione e la formula di calcolo una volta sola e in futuro i vostri clienti potranno ordinare i pezzi da voi in pochi secondi.","og_url":"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/","og_site_name":"WiCAM","article_modified_time":"2024-05-28T13:09:11+00:00","og_image":[{"url":"https:\/\/www.wicam.com\/wp-content\/uploads\/2022\/03\/cloud-300x278.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/","url":"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/","name":"CAD\/CAM Nesting Software - Calcolo locale - PNCalculate - WiCAM","isPartOf":{"@id":"https:\/\/wicam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/#primaryimage"},"image":{"@id":"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.wicam.com\/wp-content\/uploads\/2022\/03\/cloud-300x278.png","datePublished":"2022-08-16T09:43:03+00:00","dateModified":"2024-05-28T13:09:11+00:00","description":"Salvate i parametri di produzione e la formula di calcolo una volta sola e in futuro i vostri clienti potranno ordinare i pezzi da voi in pochi secondi.","breadcrumb":{"@id":"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/#primaryimage","url":"https:\/\/www.wicam.com\/wp-content\/uploads\/2022\/03\/cloud-300x278.png","contentUrl":"https:\/\/www.wicam.com\/wp-content\/uploads\/2022\/03\/cloud-300x278.png"},{"@type":"BreadcrumbList","@id":"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/calcolo-locale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/wicam.com\/it\/"},{"@type":"ListItem","position":2,"name":"Software","item":"https:\/\/wicam.com\/it\/cadcam-nesting-software\/"},{"@type":"ListItem","position":3,"name":"Calcolo","item":"https:\/\/wicam.com\/it\/cadcam-nesting-software\/pncalculate\/"},{"@type":"ListItem","position":4,"name":"Calcolo locale"}]},{"@type":"WebSite","@id":"https:\/\/wicam.com\/it\/#website","url":"https:\/\/wicam.com\/it\/","name":"WiCAM","description":"Technische Software","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wicam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/wicam.com\/it\/wp-json\/wp\/v2\/pages\/29181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wicam.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/wicam.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/wicam.com\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/wicam.com\/it\/wp-json\/wp\/v2\/comments?post=29181"}],"version-history":[{"count":0,"href":"https:\/\/wicam.com\/it\/wp-json\/wp\/v2\/pages\/29181\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/wicam.com\/it\/wp-json\/wp\/v2\/pages\/28917"}],"wp:attachment":[{"href":"https:\/\/wicam.com\/it\/wp-json\/wp\/v2\/media?parent=29181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}